{"id":85,"date":"2013-10-08T08:58:00","date_gmt":"2013-10-08T08:58:00","guid":{"rendered":"http:\/\/fjkoloffon.com\/anotaciones\/uncategorized\/los-primeros-42-195-kilometros-de-mi-vida\/"},"modified":"2025-05-09T20:22:48","modified_gmt":"2025-05-10T02:22:48","slug":"los-primeros-42-195-kilometros-de-mi-vida","status":"publish","type":"post","link":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/","title":{"rendered":"Los primeros 42.195 kil\u00f3metros de mi vida"},"content":{"rendered":"<div class=\"addtoany_share_save_container addtoany_content_top\">\n<div class=\"addtoany_header\">Comparte:<\/div>\n<div class=\"a2a_kit a2a_kit_size_32 addtoany_list\"><\/div>\n<\/div>\n<p>Y lleg\u00f3 el d\u00eda. Luego de tantos entrenamientos y desma\u00f1anadas, tras varias pruebas de preparaci\u00f3n, cientos de kil\u00f3metros recorridos y una semana de dieta intensiva, el 25 de agosto pasado corr\u00ed finalmente mi primer marat\u00f3n, el de la Ciudad de M\u00e9xico, ciudad en la que nac\u00ed y donde he vivido siempre. No pudo haber sido en otro sitio, yo quer\u00eda empezar aqu\u00ed esta carrera que quiz\u00e1s me llevar\u00e1 m\u00e1s lejos del Estadio Ol\u00edmpico Universitario.<\/p>\n<figure class=\"tmblr-full\"><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png\" \/><\/figure>\n<p>La alarma del celular me despert\u00f3 a las 5:15 AM, mi preocupaci\u00f3n de que no sonara s\u00f3lo desapareci\u00f3 hasta que la escuch\u00e9. Dice mi esposa que soy demasiado aprensivo, pero la verdad es que van un par de veces que el tal iPhone no suena y me quedo dormido. Por nada del mundo quer\u00eda llegar tarde.<\/p>\n<p>El taxi toc\u00f3 el timbre casi treinta minutos despu\u00e9s de la hora a la que lo ped\u00ed desde la noche antes, pero llegu\u00e9 a tiempo. A las 6:50 AM me baj\u00e9 todav\u00eda a oscuras en las calles del centro hist\u00f3rico, a unos pasos de Eje Central, por que ese y los dem\u00e1s accesos al Hemiciclo a Ju\u00e1rez estaban ya cerrados por polic\u00edas. Cinco minutos antes hab\u00edan salido los participantes en silla de ruedas.<\/p>\n<p>A las 7:00 AM empec\u00e9 a estirar y justo en ese instante comenz\u00f3 la cuenta regresiva para el bloque de las mujeres. Entonces los hombres nos preparamos y cerca de las 7:15 avanzamos a la l\u00ednea de salida. Encend\u00ed mi iPod para alistar el cron\u00f3metro y acto seguido cerr\u00e9 bien la bolsa de mis shorts, en la que guard\u00e9 tres Gu para consumir uno cada diez kil\u00f3metros. Aparte de eso s\u00f3lo cargaba conmigo el n\u00famero 9537 que asegur\u00e9 al frente de la camiseta que dise\u00f1\u00e9 especialmente para correr los primeros 42.195 kil\u00f3metros de mi vida.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/8734d9d2d16931682bcef61d36fcbc9c\/tumblr_inline_mu6eueAeV21qzi0uq.png\" alt=\"image\" \/><\/p>\n<p>Entonar el himno que toc\u00f3 la banda de la Secretar\u00eda de Marina supuso mi primer suspiro de la ma\u00f1ana y la consecuente espiraci\u00f3n de sentimientos que sirve para darle un poco de aire al llanto y postergarlo. De por s\u00ed, escuchar las notas de tu himno es emotivo, ahora, en un evento donde participas, resulta reconciliador. Aparte, llevaba un par de semanas muy sensible, tanto que en la oficina y el coche imaginaba escenas m\u00edas en pleno marat\u00f3n y los ojos se me aguadaban.<\/p>\n<p>Al cruzar la l\u00ednea de inicio me sent\u00eda bien a pesar de lo mal que hab\u00eda dormido, pues en la semana me desvel\u00e9 tontamente y el viernes que intent\u00e9 acostarme temprano no falt\u00f3 que Lorenzo se despert\u00f3 a media noche porque quer\u00eda leche, Regina de madrugada porque ten\u00eda fr\u00edo y al rato Paula porque so\u00f1\u00f3 feo. Total que no hil\u00e9 ni dos horas seguidas de sue\u00f1o y apenas dorm\u00ed, si acaso, cuatro. \u00c9l s\u00e1bado ni siquiera tres. Pero bueno, tra\u00eda buena energ\u00eda, el simple hecho de intercambiar saludos y buenos deseos con gente que no conozco me revitaliza. El ambiente era propenso para sentirse as\u00ed.<\/p>\n<p>\u201c\u00a1Arriba M\u00e9xico, arriba M\u00e9xico!\u201d escuch\u00e9 gritar con fuerza a voluntarios y familiares de algunos corredores en cuanto pis\u00e9 Reforma rumbo a Tlatelolco. Contagiado de su \u00e1nimo, lleno de emociones y de esa sensaci\u00f3n de que todo es posible que suele invadirme al correr, de inmediato son\u00f3 mi voz en <i>off<\/i>:<\/p>\n<blockquote><p>Arriba M\u00e9xico: es momento de levantarnos, de pararnos de la cama, del sill\u00f3n de la tele, de los escritorios que nos entristecen y nos vuelven infelices, de las sillas duras desde las que escuchamos discursos est\u00fapidos que de nada sirven. Es hora de que nos levantemos, de alzar los brazos y estirarnos para desentumir los sue\u00f1os y los m\u00fasculos. Es tiempo de luchar contra nosotros mismos, contra lo aparente e incluso contra el destino, por lo nuestro, por aquello que nos hace no s\u00f3lo mejores, sino \u00fanicos. Arriba, enfrent\u00e9monos al espejo y posteriormente al mundo, mostr\u00e9mosle nuestro aut\u00e9ntico rostro y nuestros anhelos m\u00e1s profundos, present\u00e9monos como realmente somos para que de verdad nos conozcan y nos respeten, usemos nuestras manos, nuestros pu\u00f1os y toda nuestra fuerza para sobresalir, para supervivir, que ya suficiente gente nada m\u00e1s sobrevive. Dediqu\u00e9monos a lo que nos enaltece, vivamos en un estado de elevaci\u00f3n. Arriba t\u00fa, arriba yo y arriba M\u00e9xico.<\/p><\/blockquote>\n<p>As\u00ed me sucede cuando corro, soy todo furor. Me inspiro, digamos. Y no soy el \u00fanico, reci\u00e9n un amigo corredor de maratones, <i>ironmans<\/i>, ultramaratones y carreras a campo traviesa de hasta cien millas, me dijo que correr transforma vidas, por ejemplo la suya, o la de las personas que entrena. Y es que correr te incita a escapar de donde no est\u00e1s a gusto. \u00c9l, una ma\u00f1ana que corr\u00eda en el Bosque de Tlalpan, me cuenta que decidi\u00f3, tal cual, hacer <i>corte de caja<\/i> a su vida e irse a vivir con su esposa a Ocean\u00eda. Hoy es feliz all\u00e1 y adem\u00e1s de correr diario en la naturaleza, acaba de renunciar a un trabajo que hab\u00eda conseguido; ahora vende salsas picantes mexicanas en m\u00e1s de setenta tiendas en Australia, mismas que en un principio elaboraba y embotellaba en su cocina: \u201c<a href=\"https:\/\/www.facebook.com\/RancheroSauce?fref=ts\" target=\"_blank\" rel=\"noopener\">Ranchero<\/a>\u201d.<\/p>\n<p>Como ya me es costumbre, los primeros kil\u00f3metros los dediqu\u00e9 a repasar internamente mis <a href=\"http:\/\/fjkoloffon.tumblr.com\/post\/57034793870\/instrucciones-para-reconectarse\" target=\"_blank\" rel=\"noopener\">instrucciones de reconexi\u00f3n<\/a> para volver a m\u00ed. Es cuando consigo unificar el cuerpo, el alma, la mente y el esp\u00edritu, que en la vida cotidiana con facilidad se me dispersan. Por eso mientras corro estoy completo, soy de nuevo uno, presente en cada una de mis dimensiones. S\u00e9 a d\u00f3nde voy y, sobre todo, a d\u00f3nde quiero ir. Y conf\u00edo en llegar all\u00e1.<\/p>\n<p>Inmerso en el silencio y una vez en sinton\u00eda conmigo, dediqu\u00e9 varios minutos a mi familia, ped\u00ed por ellos, di gracias de tenerlos y por lo generosa que es con nosotros la vida. Mi cuerpo manten\u00eda un ritmo consistente y mi alma se enorgullec\u00eda de m\u00ed, mi mente me transportaba y mi esp\u00edritu, saciado con las primeras gotas de sudor, sonre\u00eda.<\/p>\n<p>En un instante iba en el kil\u00f3metro cinco y del otro lado de la avenida los hombres l\u00edderes hab\u00edan alcanzado a buena parte de las corredoras. De inmediato surgieron los aplausos para los africanos y el peruano que los persegu\u00eda. En dos ocasiones me cruc\u00e9 con los superhombres durante el trayecto y en ambas se me rompi\u00f3 la voz al vitorearlos, la determinaci\u00f3n de sus rostros y el esfuerzo constante en sus gestos me estremeci\u00f3, como me ha ocurrido en las distintas carreras que los he visto convertirse en trenes.<\/p>\n<p>Finalmente me puse los aud\u00edfonos. Sonaba, bajo el cielo nublado del domingo, \u201c<a href=\"https:\/\/www.youtube.com\/watch?v=k0KjMK0F6b8\" target=\"_blank\" rel=\"noopener\"><i>Sunday Sun<\/i><\/a>\u201d de Beck, especialmente seleccionada, igual que todo el <i>playlist<\/i>. Esa era una de las cosas que m\u00e1s me ilusionaban del marat\u00f3n, la m\u00fasica. Tard\u00e9 por lo menos hora y media en escoger las canciones que me acompa\u00f1ar\u00edan y otro tanto en definir su orden. Le sigui\u00f3 \u201c<a href=\"https:\/\/www.youtube.com\/watch?v=QfVejpYc8Zc\" target=\"_blank\" rel=\"noopener\"><i>One Day Like This<\/i><\/a>\u201d de Elbow y para entonces me aproximaba al \u00c1ngel de la Independencia con la maravillosa sensaci\u00f3n de ser libre.<\/p>\n<p>Cada que me daba cuenta aparec\u00edan m\u00e1s personas sobre Paseo de la Reforma, gente que buscaba entre miles de corredores al suyo para transmitirle aliento. Me toc\u00f3 ver c\u00f3mo algunos los encontraban y comprob\u00e9 c\u00f3mo el amor es una fuerza motora que a unos los hace brincar de alegr\u00eda y a otros nos acelera, es un sentimiento tan poderoso que hermana a quienes ni se conocen.<\/p>\n<p>\u2013\u00a1Venga, Francisco!\u2013 exclam\u00f3 una mujer de aproximadamente cuarenta a\u00f1os sin apartarme los ojos conforme pasaba junto a ella. Yo la mir\u00e9 con cierta extra\u00f1ez sin decirle nada y me pregunt\u00e9 para mis adentros si detr\u00e1s de m\u00ed vendr\u00eda <i>su Francisco<\/i> o c\u00f3mo es que sab\u00eda mi nombre y se dirig\u00eda a m\u00ed con tal familiaridad.<\/p>\n<p>\u2013\u00a1Muchas gracias! \u2013respond\u00ed a su gesto metros despu\u00e9s cuando Dios me ilumin\u00f3 y tuve a bien recordar que debajo de mi n\u00famero de corredor ven\u00eda impreso mi nombre.<\/p>\n<p>\u2013\u00a1\u00c1nimo! \u2013y me regal\u00f3 una gran sonrisa, desinteresada, absolutamente sincera, nada m\u00e1s porque s\u00ed.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/007f6076383324be7b586175030e6087\/tumblr_inline_mu6hswIPDh1qzi0uq.jpg\" alt=\"image\" \/><\/p>\n<p>Contagiado de j\u00fabilo, prosegu\u00ed, convencido de que la sonrisa hay que ejercitarla como los m\u00fasculos, pues si permanece mucho tiempo acartonada y tiesa, se atrofia. Enseguida visualic\u00e9 mi encuentro con los m\u00edos y me estremec\u00ed. Si aquella algarab\u00eda ajena la hab\u00eda sentido tan propia, lo nuestro ser\u00eda tremendamente conmovedor. S\u00f3lo de imaginarlo se me contrajo la garganta y del ojo derecho me escurri\u00f3 una l\u00e1grima. S\u00ed, esto de las endorfinas que genera el ejercicio me tiene como a una embarazada de seis meses: como todo el santo d\u00eda, chillo por nada y por lo que sea, me dan ataques de risa, estoy hipersensible y de repente ni yo me entiendo.<\/p>\n<p>Correr me sacude de tal forma que lo que ya no quiero, \u00e1tomo a \u00e1tomo, se me cae al piso cada que mis suelas lo impactan. Supongo que por eso es que mi amigo, \u201cRanchero\u201d, dice que correr transforma vidas. Cierto es que antes yo cambi\u00e9 varias veces la m\u00eda, porque en estos trotes llevo apenas dos a\u00f1os. Primero fui abogado, luego m\u00fasico y ahora escritor, adem\u00e1s de publicista.<\/p>\n<p>En Anzures y Polanco, por ah\u00ed del kil\u00f3metro diez, una leve llovizna refresc\u00f3 el ambiente. Es sublime correr bajo la lluvia, a m\u00ed me da la oportunidad de sentirme otra vez ni\u00f1o. Los pap\u00e1s deber\u00edamos fomentar que de repente los hijos salgan al aguacero, algo de bueno traer\u00e1 consigo el agua que cae de arriba. Debo confesar que me divierte cuando los m\u00edos desobedecen a su mam\u00e1 para mojarse r\u00e1pido, en lo que ella los rega\u00f1a con las chamarras en las manos, lista para pon\u00e9rselas a la fuerza. Esa escena y la de los saltos en los charcos las disfruto.<\/p>\n<p>Aprovech\u00e9 para alzar la vista, contempl\u00e9 sobre m\u00ed las nubes grises que al sur se deste\u00f1\u00edan y agradec\u00ed el momento. Mirar all\u00e1 me tranquiliza, tendr\u00eda que levantar la cara con mayor frecuencia, me gusta hallarle forma a las nubes y me ayuda a recordar que lo que vemos ac\u00e1 abajo no es sino una parte del todo. Al regresar a tierra descubr\u00ed la se\u00f1al del kil\u00f3metro quince, me enfilaba al circuito Gandhi, a un costado del Museo de Antropolog\u00eda, donde a lo lejos vi a mi gran amigo <a href=\"https:\/\/twitter.com\/arkituro\" target=\"_blank\" rel=\"noopener\">Arturo Fern\u00e1ndez<\/a>, quien desde la orilla de la calle me buscaba, tal cual me avis\u00f3 que lo har\u00eda.<\/p>\n<p>Hoy d\u00eda es contada la gente que se levanta de la cama tan temprano en domingo nada m\u00e1s para ver correr a un amigo. \u201cEl Arqui\u201d, como es mejor conocido, es de esos poqu\u00edsimos. Nos conocimos hace seis a\u00f1os por azares del destino, cuando mi papel de abogado, que por aquella \u00e9poca lo combinaba con una suerte de disquero y manager de grupos, llegaba a su fin. Detestaba las leyes, me hac\u00edan sentir ilegal, as\u00ed que tuve que inventarme con urgencia un oficio porque mi segunda hija estaba por nacer. Opt\u00e9 por ese al que recurrimos muchos de los que no tenemos pu\u00f1etera idea de qu\u00e9 hacer con nuestra vida: publicista.<\/p>\n<p>En gran parte gracias a Arturo pude asumir la m\u00e1s reciente faceta de mi existencia, a la fecha sus consejos profesionales, y ocasionalmente de matrimonio, me son invaluables. Sin ninguna reserva me transmiti\u00f3 su experiencia en la oficina y me advirti\u00f3 de ciertos errores comunes que gracias a \u00e9l elud\u00ed. Me present\u00f3 personajes del medio, a sus amigos y hasta a sus hermanos, me ense\u00f1\u00f3 a analizar presupuestos de producci\u00f3n, a cambiar de encuadre e, inclusive, de enfoque. Es un experto en mandar gente al diablo, si algo no le parece sencillamente les dice \u201cno\u201d. Esa capacidad de respuesta \u00a0no se le aprende a cualquiera. Sin duda, toparte con un maestro as\u00ed te facilita la entrada a cualquier mundo desconocido, como en su momento lo fue la publicidad para m\u00ed.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/rodrigo.koloffon?fref=ts\" target=\"_blank\" rel=\"noopener\">Rodrigo mi hermano<\/a> me esperar\u00eda frente al Auditorio Nacional, en la esquina del otrora Hard Rock Caf\u00e9, alrededor del kil\u00f3metro dieciocho, donde, por cierto, atravesaba mi mejor momento con \u201c<a href=\"https:\/\/www.youtube.com\/watch?v=dmnda1keSLQ\" target=\"_blank\" rel=\"noopener\"><i>Pioneer to the Falls<\/i><\/a>\u201d de Interpol en los aud\u00edfonos. Avanzaba en calma, completo, con la respiraci\u00f3n prolongada y las piernas fuertes, a muy buen paso. De hecho, precisamente ah\u00ed rebas\u00e9 al Chapul\u00edn Colorado, que ignoro c\u00f3mo pudo correr enfundado en ese atuendo, con antenitas de vinil y chipote chill\u00f3n incluidos. A m\u00ed me dar\u00eda una <i>chiripiolca.<\/i><\/p>\n<p>\u201cEl Moe\u201d \u2013es el apodo de mi hermano desde chico\u2013 se sorprendi\u00f3 de encontrarme en tan buenas condiciones luego de los casi veinte kil\u00f3metros recorridos. No contaba con mi astucia y, de hecho, creo que ni enterado estaba de que corro, hasta que le platiqu\u00e9 del marat\u00f3n por <i>whatsapp<\/i> el viernes previo. A los dos nos dio ilusi\u00f3n vernos, a \u00e9l se lo not\u00e9 en la expresi\u00f3n del rostro y a m\u00ed en la energ\u00eda. Estas proezas perder\u00edan cierto sentido de no compartirse con los amigos y la familia.<\/p>\n<p>Mi iPod marcaba las nueve de la ma\u00f1ana cuando entr\u00e9 a Chapultepec. La presencia de tantos \u00e1rboles sac\u00f3 a pasear el instinto de perro de muchos corredores que aprovecharon para orinar cual cuadr\u00fapedos. Yo pens\u00e9 hacerlo pero tampoco me urg\u00eda y me enfoqu\u00e9 mejor en la afluencia de visitantes al parque, en los dulces que unos repart\u00edan y en el \u00e1nimo que otros nos brindaban. Yo tom\u00e9 un vaso con Gatorade en un puesto de abastecimiento y en el siguiente me dieron agua helada que me vaci\u00e9 en la cabeza. Acto seguido inger\u00ed el segundo Gu que en cuesti\u00f3n de minutos me repuso.<\/p>\n<p>En la desembocadura con Reforma, pr\u00f3ximos al kil\u00f3metro veintid\u00f3s, apareci\u00f3 de nuevo Arturo, ah\u00ed estaba de pie muy pendiente de m\u00ed y yo con los sentimientos efervescentes, con las endorfinas en un punto \u00e1lgido y el alma que me vibraba al hacerme consciente de la conexi\u00f3n con los m\u00edos y del mismo modo con los extra\u00f1os. El llanto lo apacig\u00fc\u00e9 a soplidos e inhalaciones y me desped\u00ed de \u201cEl Arqui\u201d con la mano en el coraz\u00f3n.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/cd7d371c8ae92a8428729a7b1876d6c4\/tumblr_inline_mu6lts7Udt1qzi0uq.jpg\" alt=\"image\" \/><\/p>\n<p>Continuamos de regreso por Reforma los miles de corredores y ah\u00ed, en el punto medio del trayecto, record\u00e9 las palabras de otro buen amigo, <a href=\"https:\/\/www.facebook.com\/pepe.hinojosa.731?fref=ts\" target=\"_blank\" rel=\"noopener\">Pepe Hinojosa<\/a>, que igual corre: \u201cDos medios maratones no suman uno\u201d, me previno. \u201cConsidera que la segunda mitad la inicias con el desgaste de la primera, es muy distinto a aventarte veinti\u00fan kil\u00f3metros fresco\u201d. Lo ten\u00eda claro, sin embargo no disminu\u00ed el ritmo porque me sent\u00eda bien y para llegar dentro de las cuatro horas que hab\u00eda calculado.<\/p>\n<p>En Insurgentes dimos vuelta a la derecha para encaminarnos por Avenida Chapultepec a la colonia Condesa. Escuchaba \u201c<a href=\"https:\/\/www.youtube.com\/watch?v=vl8p4qah6H8\" target=\"_blank\" rel=\"noopener\"><i>Indestructibles<\/i><\/a>\u201d, de mis amigos de La Habitaci\u00f3n Roja, cuando me adentr\u00e9 en la calle de Amsterdam. Entonces s\u00ed empec\u00e9 a sufrir el rigor de la distancia: treintai\u00fan kil\u00f3metros. Hasta ah\u00ed llevaba un promedio de cincuenta y cuatro minutos por cada diez kil\u00f3metros, pero a partir de ese punto comenzaron a extend\u00e9rseme, cada uno parec\u00edan dos y despu\u00e9s tres.<\/p>\n<p>Hab\u00eda cuidado mucho mi hidrataci\u00f3n, ni m\u00e1s ni menos de lo que deb\u00eda beber, lo mismo que los Gu, de los que me acababa de tocar el tercero y \u00faltimo. Pero, a diferencia de antes, ahora la sed no ced\u00eda y supuse que si ten\u00eda la boca seca ser\u00eda porque mi organismo requer\u00eda mayor cantidad de l\u00edquido.<\/p>\n<p>No hab\u00eda acabado de pensarlo cuando a escasos metros vi a una se\u00f1ora que generosamente repart\u00eda bolsas de pl\u00e1stico con lo que aparentaba ser Gatorade azul. Inmediatamente me acerqu\u00e9 y me dio una muy fr\u00eda que seguro acababa de sacar de la hielera. Con cuidado la romp\u00ed con los dientes en una de sus puntas y exprim\u00ed hasta la \u00faltima gota.<\/p>\n<p>Sobre la calle de Nuevo Le\u00f3n arreci\u00f3 el cansancio y ya en Insurgentes la distancia al Estadio Ol\u00edmpico me parec\u00eda lo m\u00e1s cercano al infinito. Supongo que ese es el famoso muro que Pepe Hinojosa me cont\u00f3 que padeci\u00f3 en el Marat\u00f3n de Berl\u00edn y que para m\u00ed se asemejaba a la muralla china. Ya no pod\u00eda pero sab\u00eda que en las proximidades del kil\u00f3metro treinta y seis me esperaban otros queridos amigos, <a href=\"https:\/\/twitter.com\/irnewlink\" target=\"_blank\" rel=\"noopener\">Iv\u00e1n Rocha<\/a> y <a href=\"https:\/\/twitter.com\/fringelost\" target=\"_blank\" rel=\"noopener\">la Paus<\/a>, y ello me motiv\u00f3 a persistir.<\/p>\n<p>Generosos como son, los ubiqu\u00e9 donde comienza el Parque Hundido\u00a0con una enorme hielera con botellas de Gatorade que repart\u00edan a los m\u00e1s fatigados. Fue sumamente conmovedor descubrir tantas personas dadivosas como ellos a lo largo del camino.<\/p>\n<p>Ambos se emocionaron al verme, casi tanto como yo a ellos. A Iv\u00e1n lo abrac\u00e9 en lo que \u00e9l me ajustaba el arn\u00e9s de una c\u00e1mara GoPro que me coloc\u00f3 en el pecho para grabar los \u00faltimos kil\u00f3metros de mi marat\u00f3n, cuyo desenlace desconoc\u00eda si ser\u00eda feliz o fatal. Me entusiasmo tenerlos conmigo y experiment\u00e9 con Iv\u00e1n una sensaci\u00f3n de hermandad. Me sent\u00ed inmensamente afortunado por la compa\u00f1\u00eda de mis amigos, especialmente cuando me coment\u00f3 que Arturo \u2013amigo en com\u00fan\u2013 le avis\u00f3 despu\u00e9s de verme que me encaminaba a su ubicaci\u00f3n en buenas condiciones. Fue entonces cuando hice conciencia de que uno no va solo por la vida, sino que hay toda una red que nos soporta. Y si bien es cierto que nuestra energ\u00eda nos sostiene, asimismo es verdad que la de los dem\u00e1s nos impulsa.<\/p>\n<p>\u2013\u00a1Ahora le marco a Mayu al celular para decirle que vas all\u00e1! \u2013alcanc\u00e9 a escucharlo despu\u00e9s de que nos despedimos\u2013. \u00a1Hace rato hablamos y ya te espera donde quedaron! \u00a1\u00c1nimo, amigo!<\/p>\n<p>\u2013\u00a1Te quiero, pinche Iv\u00e1n! \u2013le respond\u00ed a lo lejos, ba\u00f1ado en emociones, sudor, sentimientos, hormonas de la felicidad y bebida rehidratante.<\/p>\n<p>\u2013\u00a1Fuerza!<\/p>\n<p>A los doscientos metros un corredor cay\u00f3 al piso casi enfrente de m\u00ed en un grito de dolor por un calambre. De inmediato me acerqu\u00e9 para tratar de ayudarlo pero por suerte otros corredores se me adelantaron y le levantaron las piernas y estiraron los dedos de sus pies para calmarlo. Yo estaba bastante d\u00e9bil y con trabajos pod\u00eda conmigo, as\u00ed que continu\u00e9.<\/p>\n<p>De pronto me doli\u00f3 la ingle derecha y como por arte de magia un se\u00f1or en la pr\u00f3xima esquina me regal\u00f3 una peque\u00f1a bolsa con hielos que con toda naturalidad me acomod\u00e9 dentro de los <i>boxers<\/i>. El alivio fue instant\u00e1neo. Luego me ech\u00e9 adem\u00e1s agua, mero ah\u00ed me vaci\u00e9 f\u00e1cil medio litro, adem\u00e1s de en el cuello, la cabeza, el rostro, el pecho y la espalda. Las nubes hab\u00edan desaparecido y el sol brillaba candente, el asfalto bull\u00eda y se evaporaba en un espejismo digno de pel\u00edcula de carretera en el desierto. Enseguida abr\u00ed el Gatorade rojo de un litro que me regal\u00f3 Iv\u00e1n y le di un interminable trago que me escurr\u00eda por las comisuras.<\/p>\n<p>M\u00e1s adelante acept\u00e9 tambi\u00e9n una naranja partida a la mitad que me supo a gloria, unas uvas jugosas y\u2026 medio pl\u00e1tano\u2026 S\u00ed, medio pl\u00e1tano\u2026 Una de tantas personas amables que para esa hora hab\u00edan poblado por completo las calles me ofreci\u00f3 un pl\u00e1tano \u2013\u00a1un pl\u00e1tano!\u2013 que no acabo de entender por qu\u00e9 me com\u00ed si ni siquiera me gustan tanto. Me sucedi\u00f3 como a Ofelia en <i>El Laberinto del Fauno, <\/i>me venci\u00f3 la tentaci\u00f3n con la contundencia con que suele dominarme.<\/p>\n<p>&nbsp;<\/p>\n<p>Y es que \u00a0jur\u00e9 que la maldita banana y su mentado potasio me repondr\u00edan, pero, l\u00f3gico, antes del kil\u00f3metro treinta y ocho estaba ya sobre hidratado. O, d\u00edgase, empachado, o como sea, pero el caso es que me puse verdaderamente mal, muy mal, con ganas no s\u00f3lo de vomitar, sino de desaparecer. Consider\u00e9 seriamente la opci\u00f3n de renunciar, de abandonar la carrera y desistir, de tirarme en la banqueta a morir lento. Estuve a nada de detenerme.<\/p>\n<p>Sin embargo, a pesar del hast\u00edo, del agotamiento y del dolor en la ingle, que volv\u00eda agudo, decid\u00ed continuar. Aunque jam\u00e1s camin\u00e9, por supuesto que baj\u00e9 el ritmo, con trabajos trotaba, s\u00f3lo as\u00ed consegu\u00eda mitigar el malestar. Avanzaba poco a poco, concentrado en resistir por lo menos hasta ver a Mayu, sab\u00eda que ella me obligar\u00eda a llegar a la meta, a las \u00faltimas consecuencias de esta aventura en la que involucr\u00e9 a la familia completa. Al pensar en ella lloraba, mi mente estaba abatida, exhausta casi como mi cuerpo, as\u00ed que durante esos instantes la imagin\u00e9 exclusivamente con el coraz\u00f3n, conmovido al saberla en mi espera, con su absoluto apoyo y total entrega.<\/p>\n<p>En el kil\u00f3metro treinta y ocho vislumbr\u00e9 el Teatro de los Insurgentes y alc\u00e9 la mirada para localizarla, ah\u00ed estaba, en el punto exacto donde acordamos, pendiente y atenta. La vi dar unos peque\u00f1os brincos en mi b\u00fasqueda, entonces levant\u00e9 mi mano y la onde\u00e9 para que me distinguiera, no me sal\u00eda casi la voz y opt\u00e9 por concentrar mis esfuerzos en contener el llanto \u2013quiz\u00e1s, llorar hubiera sido buena idea para deshidratarme nada m\u00e1s un poco\u2013. Por fin me ubic\u00f3.<\/p>\n<p>Fue un alivio encontrarla, espiritual y f\u00edsico. Apenas se acerc\u00f3 le entregu\u00e9 mi iPod, el Gatorade y mi alma, necesitaba incluso deshacerme de los veinti\u00fan gramos que pesa, seg\u00fan <a href=\"https:\/\/twitter.com\/G_Arriaga\" target=\"_blank\" rel=\"noopener\">Guillermo Arriaga<\/a>. Tampoco quer\u00eda m\u00e1s m\u00fasica, estaba indigesto hasta de los o\u00eddos. La \u00faltima canci\u00f3n que escuch\u00e9 en los aud\u00edfonos fue\u00a0<i>\u201c<a href=\"http:\/\/www.youtube.com\/watch?v=aQqbCCpBJcI\" target=\"_blank\" rel=\"noopener\">Perlas<\/a>\u201d<\/i>\u00a0de El Columpio Asesino, en sinton\u00eda perfecta con mi estado, con mis errores de carrera y desaciertos de vida. Mi marat\u00f3n, porque el de cada quien es rotundamente distinto, acab\u00f3 por convertirse en una senda de redenci\u00f3n.<\/p>\n<p>\u2013\u00bfC\u00f3mo te sientes? \u2013me pregunt\u00f3 preocupada, posiblemente con la esperanza de que no necesariamente como me ve\u00eda\u2013. \u00bfC\u00f3mo vas?<\/p>\n<p>\u2013\u201cHan sido tantos los errores acumulados que podr\u00eda hacerme un collar, un collar de perlas, de grandes perlas premiadas, as\u00ed son mis perlas, mis perlas acumuladas\u201d.<\/p>\n<p>\u2013\u00a1Vas bien!<\/p>\n<p>\u2013\u201cS\u00e9 que no lo hice bien, ahora s\u00e9 que mal es lo mejor que lo puedo hacer\u201d.<\/p>\n<p>A los dos nos resbalaban las l\u00e1grimas por el rostro conforme corr\u00edamos, nos dijimos tantas cosas, nos volvimos uno. Repentinamente los sentimientos brotaban y s\u00fabito se asentaban en mi interior, los l\u00edmites f\u00edsicos que rebasaba me conduc\u00edan a los rincones m\u00e1s rec\u00f3nditos de mi interior, desde donde emanaban emociones muy profundas. La gente gritaba mi nombre con mayor \u00edmpetu, infiero por mi semblante, y cada vez m\u00e1s personas me apoyaban. Sus miradas se incrustaban en la m\u00eda como impulsos voluntarios de conexi\u00f3n que me adentraron de nuevo en esa dimensi\u00f3n m\u00e1gica de unidad que se abre cuando dos o m\u00e1s corazones se sincronizan.<\/p>\n<p>Me cuesta comprender a las personas que evitan mirar a los ojos, en la oficina hay un se\u00f1or que ni para saludar da la cara, simplemente dice \u201chola\u201d y en autom\u00e1tico clava la mirada al piso o a la pared. Pienso que probablemente se deba a que de reci\u00e9n nacido no lo contemplaron, o desconozco a qu\u00e9, pero es dif\u00edcil establecer un v\u00ednculo con alguien que se cierra as\u00ed. Los ojos son, en efecto, las ventanas del alma, el primer contacto entre los seres.<\/p>\n<p>Entre los mismos corredores intercambi\u00e1bamos vistazos, fugaces pero directos, sin m\u00e1scaras, porque correr una distancia as\u00ed supone que uno sea quien es y punto. A los cuarenta kil\u00f3metros es dif\u00edcil permanecer en un papel que no sea el aut\u00e9ntico, el del mism\u00edsimo protagonista que vive en las entra\u00f1as, en el fondo, en el n\u00facleo. Cuando tocas las fibras musculares y las sutiles a ese nivel, la sustancia y la esencia es lo \u00fanico que sobrevive, da igual a qu\u00e9 se dedica quien corre junto, se trata sencillamente de un ser en un acto de entrega.<\/p>\n<p>Los pies me dol\u00edan mucho, las zancadas, sent\u00eda que las ingles se me desgarrar\u00edan. Segu\u00ed a trote lento, desde el inicio me impuse la consigna de no caminar ni un cent\u00edmetro. Me rebasaban viejos, chicas, gordos, rechonchas, contempor\u00e1neos y me ten\u00eda sin descuido, ni siquiera not\u00e9 que yo igual dejaba atr\u00e1s a otros. Avanzaba extenuado, con la ilusi\u00f3n de llegar no al kil\u00f3metro cuarenta y dos, mi mente estaba concentrada en el cuarenta, donde aguardaban parecidamente impacientes mis hijos, comandados por <a href=\"https:\/\/www.facebook.com\/cristina.r.senties?fref=ts\" target=\"_blank\" rel=\"noopener\">Kiki<\/a> y con los refuerzos de Mar\u00eda y Luti, sus primas. Apenas los vi, con la misma camiseta que yo, supe que pod\u00eda llegar al infinito mismo.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/f61ba7ac886ba8868865e9f4c375a4ca\/tumblr_inline_muc0ceQ74J1qzi0uq.jpg\" alt=\"image\" \/><\/p>\n<p>Yo ya hab\u00eda ganado, ah\u00ed estaban todos ellos demostr\u00e1ndomelo, gritaban, re\u00edan, me echaban porras, corr\u00edan conmigo. Regina, mi hija grande, puso cara de angustia al notar que lloraba. Intent\u00e9 ocultarlo, mas el sentimiento me desbord\u00f3. Luego pens\u00e9 que tampoco est\u00e1 mal que los hijos vean as\u00ed a sus padres, emocionados, libres, vulnerables. El llanto que es mezcla de amor y esfuerzo es una especie de cascada que limpia y devuelve cierto brillo, una corriente que termina por arrastrar a quien la experimenta hasta su lago interno, donde lo \u00faltimo que queda es flotar.<\/p>\n<p>As\u00ed continu\u00e9 la marcha los \u00faltimos dos kil\u00f3metros, estremecido, transportado por mi familia, empujado literalmente por mi esposa, por la gente, por la inercia de mis piernas, por el tes\u00f3n del esp\u00edritu. Lloraba incluso porque me conmov\u00eda de m\u00ed mismo, del esfuerzo, de la entrega, del sufrimiento y del gozo. Entretanto, mis amigos segu\u00edan pendientes de m\u00ed en Twitter y mis padres en el tel\u00e9fono de Mayu, tristes de que no consiguieron cruzar la ciudad a tiempo para acompa\u00f1ar en el kil\u00f3metro cuarenta a Regina, Paula y Lorenzo. Sin embargo, ven\u00edan conmigo.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/0cb4ff3b6361a69cb0e206ba7ba31a53\/tumblr_inline_mucngzPTeX1qzi0uq.jpg\" alt=\"image\" \/><\/p>\n<p>Antes de llegar al estadio pens\u00e9 que bajo ninguna circunstancia deseaba acabar mi vida as\u00ed de cansado, y es que el marat\u00f3n es un poco un reflejo de c\u00f3mo se vive. El final debe ser tranquilo, hay que disfrutar el desenlace tanto como el comienzo o la parte de en medio. Tengo que descansar m\u00e1s, ir a mi ritmo, ejercitar la fuerza de voluntad y cerrar la boca. Imagino que mientras m\u00e1s \u00edntegro concluyes mayor, es la satisfacci\u00f3n.<\/p>\n<p>Conforme atravesaba el t\u00fanel agradec\u00ed terminar en compa\u00f1\u00eda de mi mujer y s\u00f3lo entonces silenci\u00e9 todos mis pensamientos. Era hora de enterrar lo que ya no serv\u00eda de m\u00ed y salir a la luz. Con el sol en la cara dese\u00e9 con todas mis fuerzas una nueva vida, una nueva oportunidad, una nueva ruta.<\/p>\n<p>Esos fueron los primeros 42.195 kil\u00f3metros de mi vida, despu\u00e9s de los cuales puedo afirmar que todo el camino es simplemente para llegar a uno.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/2900490b22f31bbea6368921a4a92a74\/tumblr_inline_muc00use7x1qzi0uq.jpg\" alt=\"image\" \/><\/p>\n<p>4:24:59<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/ff333de5b20a6715475e50e1ea84492b\/tumblr_inline_mubzzyfslF1qzi0uq.jpg\" alt=\"image\" \/><\/p>\n<p>Y al d\u00eda siguiente, con el cuerpo adolorido y el \u00e1nimo golpeado por la nostalgia de que todo hab\u00eda acabado, recib\u00ed un mensaje lleno de amor (de madre). Habr\u00e9 de entrenar para la pr\u00f3xima llegar antes.<\/p>\n<figure class=\"tmblr-full\"><img decoding=\"async\" src=\"http:\/\/68.media.tumblr.com\/7d7a58a8fb8b3da9c3130f5ce242dcbf\/tumblr_inline_ntrpr9XwOY1qzi0uq_540.png\" alt=\"image\" \/><\/figure>\n<div class=\"addtoany_share_save_container addtoany_content_bottom\">\n<div class=\"addtoany_header\">Comparte:<\/div>\n<div class=\"a2a_kit a2a_kit_size_32 addtoany_list\"><\/div>\n<\/div>\n<p class=\"tumblr-crosspostr-linkback\"><a title=\"Go to the original post.\" href=\"http:\/\/fjkoloffon.com\/blog\/los-primeros-42-195-kilometros-de-mi-vida\/\" target=\"_blank\" rel=\"bookmark noopener\">Los primeros 42.195 kil\u00f3metros de mi vida.<\/a> was originally published on <a href=\"http:\/\/fjkoloffon.com\/blog\" target=\"_blank\" rel=\"noopener\">FJ KOLOFFON<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comparte: Y lleg\u00f3 el d\u00eda. Luego de tantos entrenamientos y desma\u00f1anadas, tras varias pruebas de preparaci\u00f3n, cientos de kil\u00f3metros recorridos y una semana de dieta&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[174,175,131,38,7,176,36,59,177,52,178,41,179],"class_list":["post-85","post","type-post","status-publish","format-standard","hentry","category-anotaciones-de-un-astronauta-terrestre","tag-174","tag-42-195-km","tag-corredores","tag-correr","tag-fj-koloffon","tag-kilometros","tag-koloffon","tag-maraton","tag-maraton-ciudad-de-mexico","tag-maratoncdmx","tag-meta","tag-running","tag-unidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Los primeros 42.195 kil\u00f3metros de mi vida - FJ KOLOFFON<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los primeros 42.195 kil\u00f3metros de mi vida\" \/>\n<meta property=\"og:description\" content=\"Comparte: Y lleg\u00f3 el d\u00eda. Luego de tantos entrenamientos y desma\u00f1anadas, tras varias pruebas de preparaci\u00f3n, cientos de kil\u00f3metros recorridos y una semana de dieta&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"FJ KOLOFFON\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-08T08:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-10T02:22:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png\" \/>\n<meta name=\"author\" content=\"FJ Koloffon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FJ Koloffon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\"},\"author\":{\"name\":\"FJ Koloffon\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742\"},\"headline\":\"Los primeros 42.195 kil\u00f3metros de mi vida\",\"datePublished\":\"2013-10-08T08:58:00+00:00\",\"dateModified\":\"2025-05-10T02:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\"},\"wordCount\":4689,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png\",\"keywords\":[\"42\",\"42.195 km\",\"corredores\",\"Correr\",\"FJ Koloffon\",\"kil\u00f3metros\",\"Koloffon\",\"marat\u00f3n\",\"marat\u00f3n ciudad de m\u00e9xico\",\"maratoncdmx\",\"meta\",\"Running\",\"unidad\"],\"articleSection\":[\"Anotaciones de un astronauta terrestre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\",\"name\":\"Los primeros 42.195 kil\u00f3metros de mi vida - FJ KOLOFFON\",\"isPartOf\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png\",\"datePublished\":\"2013-10-08T08:58:00+00:00\",\"dateModified\":\"2025-05-10T02:22:48+00:00\",\"author\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742\"},\"breadcrumb\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage\",\"url\":\"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png\",\"contentUrl\":\"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fjkoloffon.com\/anotaciones\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los primeros 42.195 kil\u00f3metros de mi vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#website\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/\",\"name\":\"FJ KOLOFFON\",\"description\":\"ANOTACIONES DE UN ASTRONAUTA TERRESTRE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fjkoloffon.com\/anotaciones\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742\",\"name\":\"FJ Koloffon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png\",\"contentUrl\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png\",\"caption\":\"FJ Koloffon\"},\"sameAs\":[\"http:\/\/fjkoloffon.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los primeros 42.195 kil\u00f3metros de mi vida - FJ KOLOFFON","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/","og_locale":"es_ES","og_type":"article","og_title":"Los primeros 42.195 kil\u00f3metros de mi vida","og_description":"Comparte: Y lleg\u00f3 el d\u00eda. Luego de tantos entrenamientos y desma\u00f1anadas, tras varias pruebas de preparaci\u00f3n, cientos de kil\u00f3metros recorridos y una semana de dieta&hellip;","og_url":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/","og_site_name":"FJ KOLOFFON","article_published_time":"2013-10-08T08:58:00+00:00","article_modified_time":"2025-05-10T02:22:48+00:00","og_image":[{"url":"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png","type":"","width":"","height":""}],"author":"FJ Koloffon","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FJ Koloffon","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#article","isPartOf":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/"},"author":{"name":"FJ Koloffon","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742"},"headline":"Los primeros 42.195 kil\u00f3metros de mi vida","datePublished":"2013-10-08T08:58:00+00:00","dateModified":"2025-05-10T02:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/"},"wordCount":4689,"commentCount":0,"image":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage"},"thumbnailUrl":"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png","keywords":["42","42.195 km","corredores","Correr","FJ Koloffon","kil\u00f3metros","Koloffon","marat\u00f3n","marat\u00f3n ciudad de m\u00e9xico","maratoncdmx","meta","Running","unidad"],"articleSection":["Anotaciones de un astronauta terrestre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/","url":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/","name":"Los primeros 42.195 kil\u00f3metros de mi vida - FJ KOLOFFON","isPartOf":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage"},"image":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage"},"thumbnailUrl":"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png","datePublished":"2013-10-08T08:58:00+00:00","dateModified":"2025-05-10T02:22:48+00:00","author":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742"},"breadcrumb":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#primaryimage","url":"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png","contentUrl":"http:\/\/68.media.tumblr.com\/2b18d8f78e3761a065e67f4ff7b2e0de\/tumblr_inline_ntrqt7YXaW1qzi0uq_540.png"},{"@type":"BreadcrumbList","@id":"https:\/\/fjkoloffon.com\/anotaciones\/los-primeros-42-195-kilometros-de-mi-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fjkoloffon.com\/anotaciones\/"},{"@type":"ListItem","position":2,"name":"Los primeros 42.195 kil\u00f3metros de mi vida"}]},{"@type":"WebSite","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#website","url":"https:\/\/fjkoloffon.com\/anotaciones\/","name":"FJ KOLOFFON","description":"ANOTACIONES DE UN ASTRONAUTA TERRESTRE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fjkoloffon.com\/anotaciones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742","name":"FJ Koloffon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/image\/","url":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png","contentUrl":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png","caption":"FJ Koloffon"},"sameAs":["http:\/\/fjkoloffon.com"]}]}},"_links":{"self":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":1,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts\/85\/revisions"}],"predecessor-version":[{"id":3351,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts\/85\/revisions\/3351"}],"wp:attachment":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/media?parent=85"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/categories?post=85"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/tags?post=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}