{"id":2616,"date":"2022-05-03T17:39:07","date_gmt":"2022-05-03T22:39:07","guid":{"rendered":"https:\/\/fjkoloffon.com\/anotaciones\/?p=2616"},"modified":"2022-06-26T22:59:15","modified_gmt":"2022-06-27T03:59:15","slug":"como-sera-mi-vida-dentro-de-cuatro","status":"publish","type":"post","link":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/","title":{"rendered":"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?"},"content":{"rendered":"<p class=\"p1\">Inevitablemente, cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n se encontrar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde estar\u00e9 viviendo?, \u00bfme quedar\u00e1 todav\u00eda pelo?, \u00bfcu\u00e1nto dinero tendr\u00e9 en el banco?, \u00bfhabr\u00e9 publicado otra novela?, \u00bfun cuento?, \u00bfseguir\u00e9 corriendo a buen ritmo?, \u00bfcon qui\u00e9n estar\u00e9 viendo el partido inaugural del pr\u00f3ximo mundial de futbol?, \u00bfser\u00e1 en una pantalla o en la tribuna?<\/p>\n<p class=\"p1\">Soy muy dado a pensar en el futuro, a imaginar d\u00f3nde me encontrar\u00e9 en cierto tiempo, y la <strong>Copa Mundial de la FIFA<\/strong> es una buena referencia. Cuatro a\u00f1os es un periodo considerable para que sucedan cosas importantes, para que la vida te lleve a otros sitios o te quite las ganas de moverte, para consolidar proyectos y planes, para que ocurra lo m\u00e1s inesperado. Aquel hermoso partido de <strong>M\u00e9xico<\/strong> contra <strong>Alemania<\/strong>, apenas en 2018, todav\u00eda lo vi en mi casa con mi pap\u00e1. En cuatro a\u00f1os puede pasar todo.<\/p>\n<p><iframe loading=\"lazy\"  id=\"_ytid_49507\"  width=\"758\" height=\"426\"  data-origwidth=\"758\" data-origheight=\"426\" src=\"https:\/\/www.youtube.com\/embed\/EmUymgKOjAk?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n<p class=\"p1\">Desde hace varias ediciones del m\u00e1ximo torneo internacional de futbol por excelencia \u2014cuando menos cinco\u2014, de pronto un buen d\u00eda me veo ah\u00ed sentado frente al televisor mirando alguno de los partidos, y sin siquiera pensarlo me pregunto con absoluta seriedad: \u201c\u00bfY c\u00f3mo ser\u00e1 mi vida el pr\u00f3ximo mundial?\u201d.<\/p>\n<figure id=\"attachment_2622\" aria-describedby=\"caption-attachment-2622\" style=\"width: 758px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2622 size-large\" src=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/592E63A9-32D6-46B5-82B8-636E64B961D5-819x1024.jpg\" alt=\"\" width=\"758\" height=\"948\" srcset=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/592E63A9-32D6-46B5-82B8-636E64B961D5-819x1024.jpg 819w, https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/592E63A9-32D6-46B5-82B8-636E64B961D5-240x300.jpg 240w, https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/592E63A9-32D6-46B5-82B8-636E64B961D5-768x960.jpg 768w, https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/592E63A9-32D6-46B5-82B8-636E64B961D5-1229x1536.jpg 1229w, https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/592E63A9-32D6-46B5-82B8-636E64B961D5.jpg 1440w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><figcaption id=\"caption-attachment-2622\" class=\"wp-caption-text\">Siempre me ha gustado el futbol<\/figcaption><\/figure>\n<p class=\"p1\">El domingo nos toc\u00f3 juego de <strong>Lorenzo<\/strong> mi hijo a las ocho de la ma\u00f1ana, muy cerca del parque y la pista para correr de <strong>El Ocotal<\/strong>, en el <strong>Estado de M\u00e9xico<\/strong>. En las gradas los pap\u00e1s empezamos a platicar sobre <strong>Qatar<\/strong>. Que si no van a vender cervezas en los estadios por aquello de la religi\u00f3n, que si la gente tendr\u00e1 que ir a las islas del Fan Fest para pedir una copa, que si le vamos a dar la sorpresa de su vida a <strong>Argentina<\/strong>, que si el quinto partido, que si fue o no una locura organizar all\u00e1 el torneo con semejantes temperaturas. Cabe mencionar que el campeonato master de atletismo de nuestro pa\u00eds se celebra esta semana en M\u00e9rida, Yucat\u00e1n, a temperaturas cercanas a los 30\u00ba cent\u00edgrados. A veces as\u00ed es, y ya.<\/p>\n<div style=\"width: 758px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-2616-1\" width=\"758\" height=\"429\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/VIDEO-2022-05-06-17-01-58.mp4?_=1\" \/><a href=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/VIDEO-2022-05-06-17-01-58.mp4\">https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/VIDEO-2022-05-06-17-01-58.mp4<\/a><\/video><\/div>\n<p class=\"p1\">Cu\u00e1nta curiosidad genera el futuro, el no saber a ciencia cierta lo que nos deparar\u00e1 el destino. El desconocimiento del porvenir llega a ser desconcertante, aunque en la incertidumbre se da tambi\u00e9n una sensaci\u00f3n m\u00e1gica, un misticismo que no necesariamente implica endilgarle nuestro devenir al azar o a la casualidad, sino a una convicci\u00f3n muy particular de que el universo es una gran cancha de infinitas posibilidades, un interminable c\u00e9sped lleno de porter\u00edas que est\u00e1n \u00e1vidas de goles.<\/p>\n<p class=\"p1\">Ya s\u00f3lo faltan unos meses para que vuelva a surgir la pregunta: \u00bfy c\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?<\/p>\n<figure id=\"attachment_2620\" aria-describedby=\"caption-attachment-2620\" style=\"width: 540px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2620 size-full\" src=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg\" alt=\"\" width=\"540\" height=\"675\" \/><figcaption id=\"caption-attachment-2620\" class=\"wp-caption-text\">Dominando la pelota. O la pelota dominando<\/figcaption><\/figure>\n<p>Estoy en\u00a0<a href=\"https:\/\/www.facebook.com\/FJKoloffon\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>,\u00a0<a href=\"https:\/\/www.instagram.com\/fjkoloffon\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>\u00a0y\u00a0<a href=\"http:\/\/twitter.com\/FJKoloffon\" target=\"_blank\" rel=\"noopener\">Twitter<\/a>. Trabajo en\u00a0<a href=\"http:\/\/koloffoneureka.com\/\" target=\"_blank\" rel=\"noopener\">Koloffon Eureka<\/a>\u00a0y en\u00a0<a href=\"http:\/\/lanoveleria.com\/\" target=\"_blank\" rel=\"noopener\">La Noveler\u00eda<\/a>.<\/p>\n<p class=\"p1\"><a href=\"http:\/\/eluniversal.com.mx\/opinion\/fj-koloffon\/y-como-sera-mi-vida-dentro-de-cuatro-anos?fbclid=IwAR1MV0OdOcjks7GT2QkjaY3yRa5_tJdkxumFPkltwsRFvPcHzPgCKVKwfBk\">Columna publicada<\/a><a href=\"http:\/\/eluniversal.com.mx\/opinion\/fj-koloffon\/y-como-sera-mi-vida-dentro-de-cuatro-anos?fbclid=IwAR1MV0OdOcjks7GT2QkjaY3yRa5_tJdkxumFPkltwsRFvPcHzPgCKVKwfBk\"> en\u00a0 el peri\u00f3dico El Universal.<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2618 size-large\" src=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/ElUniversal_YCo\u0301moSera\u0301MiVidaDentroDeCuatroAn\u0303os-203x1024.jpg\" alt=\"\" width=\"203\" height=\"1024\" srcset=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/ElUniversal_YCo\u0301moSera\u0301MiVidaDentroDeCuatroAn\u0303os-203x1024.jpg 203w, https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/ElUniversal_YCo\u0301moSera\u0301MiVidaDentroDeCuatroAn\u0303os.jpg 406w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inevitablemente, cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n se encontrar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde estar\u00e9 viviendo?, \u00bfme quedar\u00e1&hellip;<\/p>\n","protected":false},"author":4,"featured_media":2620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1501,634,1499,342,1438,7,10,346,535,36,345,1500,343,536],"class_list":["post-2616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anotaciones-de-un-astronauta-terrestre","tag-altas-temperaturas","tag-atletismo","tag-catar-2022","tag-el-tri","tag-femexfut","tag-fj-koloffon","tag-fjkoloffon","tag-futbol","tag-historias","tag-koloffon","tag-mundial","tag-qatar-2022","tag-seleccion-mexicana-de-futbol","tag-textos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os? | Por F.J. Koloffon<\/title>\n<meta name=\"description\" content=\"Cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n estar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde vivir\u00e9?, \u00bfhabr\u00e9 publicado otra novela?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?\" \/>\n<meta property=\"og:description\" content=\"Cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n estar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde vivir\u00e9?, \u00bfhabr\u00e9 publicado otra novela?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\" \/>\n<meta property=\"og:site_name\" content=\"FJ KOLOFFON\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T22:39:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-27T03:59:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FJ Koloffon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FJ Koloffon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\"},\"author\":{\"name\":\"FJ Koloffon\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742\"},\"headline\":\"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?\",\"datePublished\":\"2022-05-03T22:39:07+00:00\",\"dateModified\":\"2022-06-27T03:59:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\"},\"wordCount\":560,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg\",\"keywords\":[\"altas temperaturas\",\"atletismo\",\"catar 2022\",\"El Tri\",\"Femexfut\",\"FJ Koloffon\",\"FJKoloffon\",\"Futbol\",\"historias\",\"Koloffon\",\"Mundial\",\"qatar 2022\",\"Selecci\u00f3n Mexicana de Futbol\",\"textos\"],\"articleSection\":[\"Anotaciones de un astronauta terrestre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\",\"name\":\"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os? | Por F.J. Koloffon\",\"isPartOf\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg\",\"datePublished\":\"2022-05-03T22:39:07+00:00\",\"dateModified\":\"2022-06-27T03:59:15+00:00\",\"author\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742\"},\"description\":\"Cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n estar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde vivir\u00e9?, \u00bfhabr\u00e9 publicado otra novela?\",\"breadcrumb\":{\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg\",\"contentUrl\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg\",\"width\":540,\"height\":675,\"caption\":\"Dominando la pelota. O la pelota dominando\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fjkoloffon.com\/anotaciones\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#website\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/\",\"name\":\"FJ KOLOFFON\",\"description\":\"ANOTACIONES DE UN ASTRONAUTA TERRESTRE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fjkoloffon.com\/anotaciones\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742\",\"name\":\"FJ Koloffon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png\",\"contentUrl\":\"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png\",\"caption\":\"FJ Koloffon\"},\"sameAs\":[\"http:\/\/fjkoloffon.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os? | Por F.J. Koloffon","description":"Cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n estar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde vivir\u00e9?, \u00bfhabr\u00e9 publicado otra novela?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?","og_description":"Cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n estar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde vivir\u00e9?, \u00bfhabr\u00e9 publicado otra novela?","og_url":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/","og_site_name":"FJ KOLOFFON","article_published_time":"2022-05-03T22:39:07+00:00","article_modified_time":"2022-06-27T03:59:15+00:00","og_image":[{"width":540,"height":675,"url":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg","type":"image\/jpeg"}],"author":"FJ Koloffon","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FJ Koloffon","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#article","isPartOf":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/"},"author":{"name":"FJ Koloffon","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742"},"headline":"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?","datePublished":"2022-05-03T22:39:07+00:00","dateModified":"2022-06-27T03:59:15+00:00","mainEntityOfPage":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/"},"wordCount":560,"commentCount":0,"image":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage"},"thumbnailUrl":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg","keywords":["altas temperaturas","atletismo","catar 2022","El Tri","Femexfut","FJ Koloffon","FJKoloffon","Futbol","historias","Koloffon","Mundial","qatar 2022","Selecci\u00f3n Mexicana de Futbol","textos"],"articleSection":["Anotaciones de un astronauta terrestre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/","url":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/","name":"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os? | Por F.J. Koloffon","isPartOf":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage"},"image":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage"},"thumbnailUrl":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg","datePublished":"2022-05-03T22:39:07+00:00","dateModified":"2022-06-27T03:59:15+00:00","author":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742"},"description":"Cada cuatro a\u00f1os me pregunto qu\u00e9 ser\u00e1 de m\u00ed en cuatro a\u00f1os m\u00e1s: \u00bfqui\u00e9n estar\u00e1 junto a m\u00ed?, \u00bfd\u00f3nde vivir\u00e9?, \u00bfhabr\u00e9 publicado otra novela?","breadcrumb":{"@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#primaryimage","url":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg","contentUrl":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2022\/05\/085F0B92-D854-4412-88A3-ABEAB1935802-e1652308853810.jpg","width":540,"height":675,"caption":"Dominando la pelota. O la pelota dominando"},{"@type":"BreadcrumbList","@id":"https:\/\/fjkoloffon.com\/anotaciones\/como-sera-mi-vida-dentro-de-cuatro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fjkoloffon.com\/anotaciones\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo ser\u00e1 mi vida dentro de cuatro a\u00f1os?"}]},{"@type":"WebSite","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#website","url":"https:\/\/fjkoloffon.com\/anotaciones\/","name":"FJ KOLOFFON","description":"ANOTACIONES DE UN ASTRONAUTA TERRESTRE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fjkoloffon.com\/anotaciones\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/05a3249caf755c4976a5f7aea8d86742","name":"FJ Koloffon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fjkoloffon.com\/anotaciones\/#\/schema\/person\/image\/","url":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png","contentUrl":"https:\/\/fjkoloffon.com\/anotaciones\/wp-content\/uploads\/2019\/04\/fjkoloffon-bio-2-150x150.png","caption":"FJ Koloffon"},"sameAs":["http:\/\/fjkoloffon.com"]}]}},"_links":{"self":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts\/2616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/comments?post=2616"}],"version-history":[{"count":6,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts\/2616\/revisions"}],"predecessor-version":[{"id":2696,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/posts\/2616\/revisions\/2696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/media\/2620"}],"wp:attachment":[{"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/media?parent=2616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/categories?post=2616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fjkoloffon.com\/anotaciones\/wp-json\/wp\/v2\/tags?post=2616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}